{"text_format":"1","workbook":"xlsx","n_sheets":7,"sheets":["Volume-Based Calculator","Layout-Based Calculator","LB Calcs","Draft","Tables","Pics","Versions"],"not_rendered":{"charts":0,"images":23,"macros":1,"external_links":1,"defined_names":43,"comments":4,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Volume-Based Calculator","index":0,"n_rows":270,"n_cols":44,"rows_kept":270,"cut":false,"hidden":false,"merged":[[5,1,5,31],[11,1,11,31],[19,1,19,31],[45,1,45,31],[48,20,48,21],[48,12,48,13],[13,19,13,20],[9,23,9,25],[7,24,7,25],[7,17,7,19],[7,21,7,22],[9,18,9,22],[7,26,7,30],[9,26,9,30],[54,11,54,12],[54,3,54,4],[7,2,7,3],[9,2,9,3],[9,8,9,9],[9,10,9,14],[43,6,43,14],[7,4,7,7],[9,4,9,7],[7,13,7,14]]}
[]
[]
[]
[null,null,null,null,null,null,null,null,"Metric Units Calculator"]
[]
[null,"PROJECT DESCRIPTION"]
[]
[null,null,"Project Name:",null,null,null,null,null,"Date:",null,"/",null,"/",null,null,null,"City/State:",null,null,null,"/",null,null,null,"Phone #:"]
[]
[null,null,"Engineer:",null,null,null,null,null,"Contractor:",null,null,null,null,null,null,null,"Designed By:",null,null,null,null,null,null,"Prinsco Rep:"]
[]
[null,"DESIGN CRITERIA - BASED ON STORAGE VOLUME"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"**For Standard units, visit Prinsco.com"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF($AH$14=\"Standard\",\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,null,null,"**",null,null,null,"Metric"]
[]
[null,null,null,null,null,2000,{"$f":"IF($AH$14=\"Standard\",\"(cf)\",CONCATENATE(\"(m\",$AJ$16,\")\"))","v":"(m³)"},null,null,null,null,12.192,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,40,"%",null,null,null,null,0,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",\"(m)\")","v":"(m)"},null,null,6,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",\"(m)\")","v":"(m)"},null,0.5,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,"²","³"]
[]
[null,null,null,null,null,0,{"$f":"IF($AH$14=\"Standard\",\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,0,{"$f":"IF($AH$14=\"Standard\",\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,0,{"$f":"IF($AH$14=\"Standard\",\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,0,{"$f":"IF($AH$14=\"Standard\",\"(in)\",\"(mm)\")","v":"(mm)"}]
[]
[null,"SYSTEM LAYOUT"]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,1]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,0]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,0]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,0]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Width Calculations"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"totalvolume","numberofrows","chambersperrow"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,4312.3388671875,10,1,"max width"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,225.25,"perimeter"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"if max width > target",null,null,null,null,null,74.5,"side1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,34.75,"side2"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,20775.32421875,10,10,"add 1 to each row",null,null,null,null,null,67.425003051757813,"side3"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,26,"side4"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,20052.04296875,10,10,"take off to meet target",null,null,null,null,null,10.82500171661377,"side5"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,11.75,"side6"]
[null,null,"Min. Burial Depth:",null,null,"450 mm","WARNING: Burial Depth Too Shallow",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,4,"c",null,null,null,null,null,2420.84375,"systemfootprint"]
[]
[null,null,"Max. Burial Depth:",null,null,"2.44 m","WARNING: Burial Depth Exceeds Recommendation",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((AQ49*AQ35))","v":782.74372851848602},"nonwoven calc"]
[]
[null,"SYSTEM STORAGE & QUANTITIES",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,74.5,"trenchlength"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,0,"maxrowvolume"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,7,"numberofrows"]
[null,null,8,"of",115,"&",0,"of",0,null,null,null,2999.587158203125,null,{"$f":"IF($AH$14=\"Standard\",\"(sf)\",CONCATENATE(\"(m\",$AI$16,\")\"))","v":"(m²)"},null,785.48101806640625,{"$f":"IF($AH$14=\"Standard\",\"(cf)\",CONCATENATE(\"(m\",$AJ$16,\")\"))","v":"(m³)"},null,null,0,null,{"$f":"IF($AH$14=\"Standard\",\"(cf)\",CONCATENATE(\"(m\",$AJ$16,\")\"))","v":"(m³)"},null,1215.5382080078125,{"$f":"IF($AH$14=\"Standard\",\"(cf)\",CONCATENATE(\"(m\",$AJ$16,\")\"))","v":"(m³)"},null,null,2001.019287109375,{"$f":"IF($AH$14=\"Standard\",\"(cf)\",CONCATENATE(\"(m\",$AJ$16,\")\"))","v":"(m³)"},null,null,null,null,null,null,null,null,null,null,null,null,3.4749999046325684,"system height"]
[null,null,"rows",null,"chambers",null,"rows",null,"chambers",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,32.799999237060547,"systemwidth"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,72.5,"systemlength"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2,"rows1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,10,"chambers1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,10,"chambersperrow"]
[null,null,null,920,null,null,null,16,null,null,null,1963.6932373046875,null,{"$f":"IF($AH$14=\"Standard\",\"(cy)\",CONCATENATE(\"(m\",$AJ$16,\")\"))","v":"(m³)"},null,12731.833984375,{"$f":"IF($AH$14=\"Standard\",\"(sy)\",CONCATENATE(\"(m\",$AI$16,\")\"))","v":"(m²)"},null,null,258.40386962890625,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",CONCATENATE(\"(m)\"))","v":"(m)"},null,null,null,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",CONCATENATE(\"(m)\"))","v":"(m)"},null,null,{"$f":"IF($AH$14=\"Standard\",\"(ft)\",CONCATENATE(\"(m)\"))","v":"(m)"},null,null,{"$f":"IF($AH$14=\"Standard\",\"(sy)\",CONCATENATE(\"(m\",$AI$16,\")\"))","v":"(m²)"},null,null,null,null,null,null,null,null,null,null,null,749.92413330078125,"nonwovengeotextile"]
[]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"V-6.7"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,25000]

{"sheet":"Layout-Based Calculator","index":1,"n_rows":46,"n_cols":56,"rows_kept":46,"cut":false,"hidden":false,"merged":[[30,11,30,12],[31,11,31,12],[42,8,42,9],[38,42,38,44],[38,12,38,13],[38,19,38,20],[38,27,38,28],[38,35,38,36],[42,39,42,40],[42,33,42,34],[42,26,42,27],[42,19,42,20],[12,28,12,29],[12,37,12,38],[12,44,12,45],[12,52,12,53],[14,10,14,11],[14,19,14,20],[14,28,14,29],[14,37,14,38],[42,52,42,53],[42,45,42,46],[6,46,6,54],[6,10,6,18],[3,5,3,55],[5,10,5,18],[5,22,5,23],[5,28,5,29],[5,25,5,26],[6,23,6,29],[5,41,5,42],[5,34,5,39],[6,34,6,42],[5,46,5,54],[8,5,8,55],[11,40,11,54]]}
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Metric Units Calculator"]
[null,null,null,null,null,"PROJECT DESCRIPTION"]
[]
[null,null,null,null,null,null,null,null,null,"Project Name:",null,null,null,null,null,null,null,null,null,null,null,"Date:",null,null,"/",null,null,"/",null,null,null,null,null,"City / State:",null,null,null,null,null,null,"/",null,null,null,null,"Phone #:"]
[null,null,null,null,null,null,null,null,null,"Engineer:",null,null,null,null,null,null,null,null,null,null,null,null,"Contractor:",null,null,null,null,null,null,null,null,null,null,"Designed By:",null,null,null,null,null,null,null,null,null,null,null,"Prinsco Rep:"]
[]
[null,null,null,null,null,"DESIGN CRITERIA - BASED ON SYSTEM DIMENSIONS"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"One Value Must Be Zero"]
[null,null,null,null,null,null,null,null,null,null,4,null,null,null,null,null,null,null,null,13,null,null,null,null,null,null,null,null,40,null,"%",null,null,null,null,null,null,2,null,{"$f":"IF(Draft!$S$3=2,\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,null,5,null,{"$f":"IF(Draft!$S$3=2,\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,null,null,4,null,{"$f":"IF(Draft!$S$3=2,\"(ft)\",\"(m)\")","v":"(m)"}]
[]
[null,null,null,null,null,null,null,null,null,null,0,null,{"$f":"IF(Draft!$S$3=2,\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,null,null,0,null,{"$f":"IF(Draft!$S$3=2,\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,null,null,0,null,{"$f":"IF(Draft!$S$3=2,\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,null,null,0,null,{"$f":"IF(Draft!$S$3=2,\"(in)\",\"(mm)\")","v":"(mm)"},null,null,null,null,null,null,null,null,null,null,null,null,null,"**"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"**For Standard units, visit Prinsco.com"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,"Minimum Burial Depth",null,null,null,null,{"$f":"'LB Calcs'!I36","v":0.60960000000000003},null,"m","Warning - Burial Depth Too Shallow"]
[null,null,null,null,null,null,"Maximum Burial Depth",null,null,null,null,{"$f":"'LB Calcs'!I37","v":2.1335999999999999},null,"m","Warning - Burial Depth Too Deep"]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(Draft!S3=2, 'LB Calcs'!G9,'LB Calcs'!I9)","v":229.01262301922785},null,{"$f":"IF(Draft!$S$3=2,\"(sq.f)\",\"(sq.m)\")","v":"(sq.m)"},null,null,null,null,{"$f":"IF(Draft!$S$3=2, 'LB Calcs'!G7,'LB Calcs'!I7)","v":119.12166163079554},null,{"$f":"IF(Draft!$S$3=2,\"(cu.f)\",\"(cu.m)\")","v":"(cu.m)"},null,null,null,null,null,{"$f":"IF(Draft!$S$3=2, 'LB Calcs'!G5,'LB Calcs'!I5)","v":0},null,{"$f":"IF(Draft!$S$3=2,\"(cu.f)\",\"(cu.m)\")","v":"(cu.m)"},null,null,null,null,null,{"$f":"IF(Draft!$S$3=2, 'LB Calcs'!G4,'LB Calcs'!I4)","v":170.45706179013271},null,{"$f":"IF(Draft!$S$3=2,\"(cu.f)\",\"(cu.m)\")","v":"(cu.m)"},null,null,null,null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G8,'LB Calcs'!I8)","v":289.57872342092827},null,null,{"$f":"IF(Draft!$S$3=2,\"(cu.f)\",\"(cu.m)\")","v":"(cu.m)"}]
[]
[]
[null,null,null,null,null,"23.5\""]
[null,null,null,null,null,null,null,null,{"$f":"'LB Calcs'!G32","v":52},null,null,null,null,null,{"$f":"'LB Calcs'!G33","v":8},null,null,null,null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G10,'LB Calcs'!I10)","v":297.8044345543961},null,{"$f":"IF(Draft!$S$3=2,\"(cu.y)\",\"(cu.m)\")","v":"(cu.m)"},null,null,null,null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G11,'LB Calcs'!I11)","v":703.90297268062113},null,{"$f":"IF(Draft!$S$3=2,\"(sq.y)\",\"(sq.m)\")","v":"(sq.m)"},null,null,null,null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G40,'LB Calcs'!I40)","v":44.721615853658534},null,{"$f":"IF(Draft!$S$3=2,\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,{"$f":"IF(Draft!$S$3=2, 'LB Calcs'!G67,'LB Calcs'!I67)","v":""},null,{"$f":"IF(Draft!$S$3=2,\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,{"$f":"IF(Draft!$S$3=2, 'LB Calcs'!G70,'LB Calcs'!I70)","v":""},null,{"$f":"IF(Draft!$S$3=2,\"(ft)\",\"(m)\")","v":"(m)"},null,null,null,null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G71,'LB Calcs'!I71)","v":""},null,{"$f":"IF(Draft!$S$3=2,\"(sq.ft)\",\"(sq.m)\")","v":"(sq.m)"}]
[null,null,null,null,null,"8'"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"V-6.7"]

{"sheet":"LB Calcs","index":2,"n_rows":71,"n_cols":17,"rows_kept":71,"cut":false,"hidden":true,"merged":[]}
[null,null,null,null,null,null,null,null,"Conversion Column","Final LB Outputs","Chamber Size","Constraint Type","Pipe Diameters (IN)","# of Manifolds","Include Volume of the Manifolds","Conversions Key "]
[null,null,null,null,null,null,null,null,null,null,"HS290","LENGTH",{"$f":"IF(A4=4,\"8 in (200 mm)\",\"\")","v":""},0,"Yes","in/m",39.370100000000001]
[null,"Inputs","Inputs","inch values",null,"Outputs",null,null,null,null,"HS180","WIDTH",{"$f":"IF(A4=4,\"10 in (250 mm)\",\"\")","v":""},1,"No","ft/m",3.28]
[1,"Chamber Size",{"$f":"IF(A4=3,\"HS75\",IF(A4=2,\"HS180\",IF(A4=1,\"HS290\",\"HS31\")))","v":"HS290"},null,null,"Chamber Storage",{"$f":"IF(C4=\"HS75\",((G33*Tables!Q16)+(G32*Tables!O16)),IF(C4=\"HS180\",((G33*Tables!Q17)+(G32*Tables!O17)),IF(C4=\"HS31\",((G33*Tables!Q15)+(G32*Tables!O15)),((G33*Tables!Q18)+(G32*Tables!O18)))))","v":6019.64},"cf",{"$f":"G4/Q4","v":170.45706179013271},null,"HS75",null,"12 in. (300 mm)",2,null,"cf/cm",35.314700000000002]
[4,"Manifold size",{"$f":"IF(A5=1,8,IF(A5=2,10,IF(A5=3,12,IF(A5=4,15,IF(A5=5,18,IF(A5=6,24,IF(A5=7,30,IF(A5=8,36))))))))","v":15},null,null,"Manifold Storage",{"$f":"IF(C7=\"YES\",((((VLOOKUP(C5,Tables!C3:Q11,12,0)+A21)/12)*('LB Calcs'!C8))+('LB Calcs'!G19-(VLOOKUP(C4,Tables!C15:R18,3,0)/12)))*C6*VLOOKUP(C5,Tables!C3:S11,8,0),0)","v":0},"cf",{"$f":"G5/Q4","v":0},null,"HS31",null,{"$f":"IF(A4=4,\"\",\"15 in. (375 mm)\")","v":"15 in. (375 mm)"},null,null,"cy/cm",1.30795062]
[3,"Number of Manifolds",{"$f":"INDEX(N2:N4,A6)","v":2},null,null,"Manifold Displacement ",{"$f":"G5/VLOOKUP(C5,Tables!C2:W11,8,FALSE)*VLOOKUP(C5,Tables!C2:W11,17,FALSE)","v":0},"cf",{"$f":"G6/Q4","v":0},null,null,null,{"$f":"IF(A4=4,\"\",\"18 in. (450 mm)\")","v":"18 in. (450 mm)"},null,null,"sy/sm",1.1959900000000001]
[2,"Include Manifold Volume",{"$f":"IF(A7=1,\"YES\",\"NO\")","v":"NO"},null,null,"Stone Storage",{"$f":"((G9*G35)-G6-G4)*C10","v":4206.7457439930558},"cf",{"$f":"G7/Q4","v":119.12166163079554},null,null,null,{"$f":"IF(A4=4,\"\",\"24 in. (600 mm)\")","v":"24 in. (600 mm)"},null,null,"sf/sm",10.7639]
[null,"Number of Rows",{"$f":"'Layout-Based Calculator'!K13","v":4},null,null,"Total Storage",{"$f":"G4+G5+G7","v":10226.385743993056},"cf",{"$f":"G8/Q4","v":289.57872342092827},null,null,null,null,null,null,"in/mm",3.9370000000000002E-2]
[null,"Number of Chambers Per Row",{"$f":"'Layout-Based Calculator'!T13","v":13},null,null,"System Footprint",{"$f":"G21*G20","v":2465.0689729166666},"sf",{"$f":"G9/Q7","v":229.01262301922785},null,null,null,{"$f":"IF(A4=4,\"\",IF(A4=1,\"\",IF(A4=2,\"\",\"36 in. (900 mm)\")))","v":""}]
[{"$f":"'Layout-Based Calculator'!AC13","v":40},"Stone Porosity",{"$f":"A10/100","v":0.4},null,null,"Required Backfill (Embedment)",{"$f":"((G9*G35)-G6-G4)/27","v":389.51349481417179},"CY",{"$f":"G10/Q5","v":297.8044345543961},null,null,null,null,null,null,"Conversion labels"]
[null,"Additional Stone Below Chamber",{"$f":"'Layout-Based Calculator'!T15","v":0},{"$f":"IF(Draft!$S$3=2,'LB Calcs'!C11*1,'LB Calcs'!C11/$Q$2)","v":0},null,"Non-Woven Geotextile (System Perimeter)",{"$f":"IF(A19=1,(((G9*2)+(G20*2+G21*2)*G35)*1.2)/9,((((G9*2)+(G20*2+G21*2)*G35)*1.2*2)-G9)/9)","v":841.86091629629618},"SY",{"$f":"G11/Q6","v":703.90297268062113},null,"System Type","Thermoplastic Liner",null,null,null,"in",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!P12,'LB Calcs'!P13)","v":"m"}]
[null,"Additional Stone Above Chamber ",{"$f":"'Layout-Based Calculator'!K15","v":0},{"$f":"IF(Draft!$S$3=2,'LB Calcs'!C12*1,'LB Calcs'!C12*$Q$8)","v":0},null,"Chamber Length",{"$f":"IF(C4=\"HS180\",Tables!F17/12,IF(C4=\"HS75\",Tables!F16/12,IF(C4=\"HS31\",Tables!F15/12,Tables!F18/12)))","v":4.0249999999999995},null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G13,G13/$Q$3)","v":17.597088414634147},{"$f":"ROUND(I12,1)&\" \"&$Q$11","v":"17.6 m"},"Retention",null,null,null,null,"ft",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!P11,'LB Calcs'!P14)","v":"mm"}]
[null,"Additional Stone Side of Chamber",{"$f":"'Layout-Based Calculator'!AC15","v":0},{"$f":"IF(Draft!$S$3=2,'LB Calcs'!C13*1,'LB Calcs'!C13*$Q$8)","v":0},null,"System Length (w/o Manifolds)",{"$f":"((C9*G12)+(2*IF(C4=\"HS75\",Tables!P16,IF(C4=\"HS180\",Tables!P17,IF(C4=\"HS31\",Tables!P15,Tables!P18))))/12)","v":57.718449999999997},"ft",null,null,"Detention",{"$f":"IF($A$19=1,\"\",\"10 mil\")","v":""},null,null,null,"m"]
[null,"Additional Spacing Between Chamber",{"$f":"'Layout-Based Calculator'!AL15","v":0},{"$f":"IF(Draft!$S$3=2,'LB Calcs'!C14*1,'LB Calcs'!C14*$Q$8)","v":0},null,"Endcap Stub Lenth (1 side)",{"$f":"(IF(C4=\"HS290\",VLOOKUP(C5,Tables!C3:W11,21,TRUE),IF(C4=\"HS180\",(VLOOKUP(C5,Tables!C3:W11,20,TRUE)),IF(C4=\"HS75\",(VLOOKUP(C5,Tables!C3:W11,19,TRUE)),(VLOOKUP(C5,Tables!C3:W11,18,FALSE)))))/12)","v":0.96833333333333327},"ft",{"$f":"IF(C6>0,G18+(C6*1),G13+(IF(OR(C4=\"HS75\",\"HS180\"),1,2)))","v":65.516783333333336},null,null,{"$f":"IF($A$19=1,\"\",\"20 mil\")","v":""},null,null,null,"mm"]
[null,"Remove Number of Chambers",{"$f":"A15","v":0},null,null,"Manifold Tee/Elbow Overall Length (1 side)",{"$f":"(VLOOKUP(C5,Tables!C3:W11,14,FALSE)/12)","v":1.9308333333333334},"ft",null,null,null,{"$f":"IF($A$19=1,\"\",\"30 mil\")","v":""}]
[2,"High Rim Elevation",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!D16,'LB Calcs'!D16*'LB Calcs'!$L$18)","v":0},{"$f":"'Layout-Based Calculator'!AS13","v":5},null,null,null,"ft",null,null,null,{"$f":"IF($A$19=1,\"\",\"40 mil\")","v":""}]
[{"$f":"'Layout-Based Calculator'!BA13","v":4},"Low Rim Elevation",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!D17,'LB Calcs'!D17*'LB Calcs'!$L$18)","v":0},{"$f":"'Layout-Based Calculator'!BA13","v":4},null,null,null,"ft",null,null,null,{"$f":"IF($A$19=1,\"\",\"60 mil\")","v":""}]
[{"$f":"'Layout-Based Calculator'!AL13","v":2},"Bottom of Stone (Bottom of System)",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!D18,'LB Calcs'!D18*'LB Calcs'!$L$18)","v":0},{"$f":"'Layout-Based Calculator'!AL13","v":2},null,"System Length (w/ Manifolds)",{"$f":"G13+G14*C6+G15*C6","v":63.516783333333329},"ft"]
[1,"System Type",null,null,null,"System Width",{"$f":"((C8*G23)+((C8-1)*G22))/12","v":35.625},"ft",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G19,G19/$Q$3)","v":10.861280487804878},{"$f":"ROUND(I19,1)&\" \"&$Q$11","v":"10.9 m"}]
[2,"Liner Type",null,null,null,"Trench Length",{"$f":"G18+2","v":65.516783333333336},"ft",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G20,G20/$Q$3)","v":19.974629065040652},{"$f":"ROUND(I20,1)&\" \"&$Q$11","v":"20 m"}]
[{"$f":"VLOOKUP(C5,Tables!C2:W11,C21,FALSE)","v":11.62},"Endcap Stub Length",{"$f":"IF(C4=\"HS290\",21,IF(C4=\"HS180\",20,IF(C4=\"HS75\",19,18)))","v":21},null,null,"Trench Width",{"$f":"(G19+(2*(G24/12)))+(2*(A13/12))+((C8-1)*(A14/12))","v":37.625},"ft",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G21,G21/$Q$3)","v":11.471036585365855},{"$f":"ROUND(I21,1)&\" \"&$Q$11","v":"11.5 m"}]
[null,null,null,null,null,"Spacing Between Chambers",{"$f":"(IF(C4=\"HS75\",Tables!H16,IF(C4=\"HS180\",Tables!H17,IF(C4=\"HS31\",Tables!H15,Tables!H18))))+$D$14","v":8.5},"in",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G22,G22/$Q$8)","v":215.9004318008636},{"$f":"ROUND(I22,1)&\" \"&$Q$12","v":"215.9 mm"}]
[null,null,null,null,null,"Chamber Width",{"$f":"IF(C4=\"HS75\",Tables!E16,IF(C4=\"HS180\",Tables!E17,IF(C4=\"HS31\",Tables!E15,Tables!E18)))","v":100.5},"in",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G23,G23/$Q$8)","v":2552.7051054102108},{"$f":"ROUND(I23,1)&\" \"&$Q$12","v":"2552.7 mm"}]
[null,null,{"$f":"G5/VLOOKUP(C5,Tables!C2:W11,8)*VLOOKUP(C5,Tables!C2:W11,17)","v":0},null,null,"End Stone (Chamber)",{"$f":"(IF(C4=\"HS75\",Tables!I16,IF(C4=\"HS180\",Tables!I17,IF(C4=\"HS31\",Tables!I15,Tables!I18))))+$D$13","v":12},"in",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G24,G24/$Q$8)","v":304.80060960121921},{"$f":"ROUND(I24,0)&\" \"&$Q$12","v":"305 mm"}]
[null,null,{"$f":"IF(C7=\"YES\",(((VLOOKUP(C5,Tables!C3:Q11,12,0)/12)*('LB Calcs'!C8-1))+('LB Calcs'!G19-(VLOOKUP(C4,Tables!C15:R18,3,0)/12)))*C6*VLOOKUP(C5,Tables!C3:S11,17,0),0)","v":0},null,null,"End Stone (End Cap)",{"$f":"IF(C4=\"HS75\",Tables!J16,IF(C4=\"HS180\",Tables!J17,IF(C4=\"HS31\",Tables!J15,Tables!J18)))","v":12},"in",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G25,G25/$Q$8)","v":304.80060960121921}]
[null,null,null,null,null,"Bedding Height",{"$f":"(IF(C4=\"HS75\",VLOOKUP(\"HS75\",Tables!C15:R18,9,FALSE),IF(C4=\"HS180\",VLOOKUP(\"HS180\",Tables!C15:R18,9,FALSE),IF(C4=\"HS31\",VLOOKUP(\"HS31\",Tables!C15:R18,9,FALSE),VLOOKUP(\"HS290\",Tables!C15:R18,9,FALSE)))))+$D$11","v":9},"ft",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G26,G26/$Q$8)","v":228.60045720091438},{"$f":"ROUND(I26,0)&\" \"&$Q$12","v":"229 mm"}]
[null,null,null,null,null,"Chamber Height",{"$f":"(IF(C4=\"HS75\",VLOOKUP(\"HS75\",Tables!C15:R18,2,FALSE),IF(C4=\"HS180\",VLOOKUP(\"HS180\",Tables!C15:R18,2,FALSE),IF(C4=\"HS31\",VLOOKUP(\"HS31\",Tables!C15:R18,2,FALSE),VLOOKUP(\"HS290\",Tables!C15:R18,2,FALSE)))))","v":59.5},null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G27,G27/$Q$8)","v":1511.303022606045},{"$f":"ROUND(I27,0)&\" \"&$Q$12","v":"1511 mm"}]
[null,null,null,null,null,"Embedment Height",{"$f":"(IF(C4=\"HS75\",VLOOKUP(\"HS75\",Tables!C15:R18,10,FALSE),IF(C4=\"HS180\",VLOOKUP(\"HS180\",Tables!C15:R18,10,FALSE),IF(C4=\"HS31\",VLOOKUP(\"HS31\",Tables!C15:R18,10,FALSE),VLOOKUP(\"HS290\",Tables!C15:R18,10,FALSE)))))+D12","v":12},null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G28,G28/$Q$8)","v":304.80060960121921},{"$f":"ROUND(I28,0)&\" \"&$Q$12","v":"305 mm"}]
[null,null,null,null,null,"Initial Backfill height",{"$f":"MAX(0,(IF(C4=\"HS75\",VLOOKUP(\"HS75\",Tables!C15:R18,11,FALSE),IF(C4=\"HS180\",VLOOKUP(\"HS180\",Tables!C15:R18,11,FALSE),IF(C4=\"HS31\",VLOOKUP(\"HS31\",Tables!C15:R18,11,FALSE),VLOOKUP(\"HS290\",Tables!C15:R18,11,FALSE))))-G28))","v":12},"ft",{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G29,G29/$Q$8)","v":304.80060960121921},{"$f":"ROUND(I29,0)&\" \"&$Q$12","v":"305 mm"}]
[null,null,null,null,null,"Min cover height above chamber",{"$f":"(IF(C4=\"HS75\",VLOOKUP(\"HS75\",Tables!C15:R18,11,FALSE),IF(C4=\"HS180\",VLOOKUP(\"HS180\",Tables!C15:R18,11,FALSE),IF(C4=\"HS31\",VLOOKUP(\"HS31\",Tables!C15:R18,11,FALSE),VLOOKUP(\"HS290\",Tables!C15:R18,11,FALSE)))))","v":24},null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G30,G30/$Q$8)","v":609.60121920243841},{"$f":"ROUND(I30,0)&\" \"&$Q$12","v":"610 mm"}]
[null,null,null,null,null,"Final Backfill Height",{"$f":"(((D16+D17)/2)-D18)-#REF!","v":{"$error":"#REF!"}},"in"]
[null,null,null,null,null,"Number of Chambers",{"$f":"(C8*C9)-C15","v":52}]
[null,null,null,null,null,"Number of End Caps",{"$f":"C8*2","v":8}]
[null,null,null,null,null,"End Cap Length",{"$f":"IF(C4=\"HS180\",Tables!P17/12,IF(C4=\"HS75\",Tables!P16/12,IF(C4=\"HS31\",Tables!P15/12,Tables!P18/12)))","v":2.6967250000000003},null,{"$f":"IF(Draft!$S$3=2,'LB Calcs'!G36,G36/$Q$8)","v":609.60121920243841},{"$f":"ROUND(I34,0)&\" \"&$Q$12","v":"610 mm"}]
[null,null,null,null,null,"Stone Height ",{"$f":"(G26+G27+G28)/12","v":6.708333333333333}]
[null,null,null,null,null,"Min. Burial Depth",{"$f":"ROUND((VLOOKUP(C4,Tables!C15:Q18,11,0)),0)","v":24},{"$f":"G36/12","v":2},{"$f":"CONVERT(H36,\"ft\",\"m\")","v":0.60960000000000003},"m",null,"=VLOOKUP(C4,Tables!C15:Q18,11,0)"]
[null,null,null,null,null,"Max. Burial Depth",{"$f":"VLOOKUP(C4,Tables!C15:S18,17,FALSE)","v":7},"ft",{"$f":"CONVERT(G37,\"ft\",\"m\")","v":2.1335999999999999},"m"]
[]
[null,null,null,null,null,"Woven Geotextile scour",{"$f":"(G19-(G23/12))","v":27.25},"ft",{"$f":"IF(Draft!$S$3=2,G39,G39/Q3)","v":8.3079268292682933},{"$f":"G39/Q6","v":22.784471442068913}]
[null,null,null,null,null,"Woven Geotextile total length w/ 1 sediment row",{"$f":"IF(C4=\"HS290\",(G13+2)*2+G39,(G13+2)+G39)","v":146.68689999999998},"ft",{"$f":"IF(Draft!$S$3=2,G40,G40/Q3)","v":44.721615853658534},{"$f":"G40/Q6","v":122.64893519176579}]
[]
[null,null,null,null,null,"Picture Selector ",{"$f":"IF(C6=2,\"DM\",\"SM\")","v":"DM"}]
[]
[null,null,null,null,null,"Additional Calculations (Standard)"]
[null,null,null,null,null,"Min Burial Depth Needed",{"$f":"($G$26+$G$27+$G$29+$G$28)/12","v":7.708333333333333},"ft"]
[null,null,null,null,null,"Max RIM ",{"$f":"'Layout-Based Calculator'!AS13:AT13","v":5},0]
[null,null,null,null,null,"Min RIM",{"$f":"'Layout-Based Calculator'!BA13:BB13","v":4},0]
[null,null,null,null,null,"Bottom of Bedding Elevation",{"$f":"'Layout-Based Calculator'!AL13:AM13","v":2},0]
[null,null,null,null,null,"Min Allowed Elevation",{"$f":"G48+G45","v":9.7083333333333321}]
[null,null,null,null,null,"Max Allowed Elevation",{"$f":"G48+G37+(($G$26+$G$27)/12)","v":14.708333333333332}]
[null,null,null,null,null,"Max. Burial Depth Check",{"$f":"IF(G50>=G46, \"Yes\",\"No\")","v":"Yes"}]
[null,null,null,null,null,"Min. Burial Depth Check",{"$f":"IF(G49<=G47, \"Yes\",\"No\")","v":"No"}]
[null,null,null,null,null,"Min height above chamber",{"$f":"ROUND(G47-((G26+G27))/12,1)","v":-1.7}]
[null,null,null,null,null,"Max height above chamber",{"$f":"ROUND(G46-((G26+G27))/12,1)","v":-0.7}]
[null,null,null,null,null,"Additional Calculations (Metric)",null,null,"Max. Burial Depth Check",{"$f":"IF(Draft!$S$3=2,(IF(G50>=G46, \"Yes\",\"No\")),(IF(G61>=G57,\"Yes\",\"No\")))","v":"Yes"},"max 51"]
[null,null,null,null,null,"Min Burial Depth Needed",{"$f":"(($G$26+$G$27+$G$29+$G$28)/12)/Q3","v":2.3501016260162602},null,"Min. Burial Depth Check",{"$f":"IF(Draft!$S$3=2,(IF(G49<=G47,\"Yes\",\"No\")),(IF(G60<=G58,\"Yes\",\"No\")))","v":"No"},"min 52"]
[null,null,null,null,null,"Max RIM ",{"$f":"'Layout-Based Calculator'!AS13:AT13","v":5},0]
[null,null,null,null,null,"Min RIM",{"$f":"'Layout-Based Calculator'!BA13:BB13","v":4},0]
[null,null,null,null,null,"Bottom of Bedding Elevation",{"$f":"'Layout-Based Calculator'!AL13:AM13","v":2},0]
[null,null,null,null,null,"Min Allowed Elevation",{"$f":"G59+G56","v":4.3501016260162597}]
[null,null,null,null,null,"Max Allowed Elevation",{"$f":"G59+I37+(($I$26+$I$27)/1000)","v":5.873503479806959},{"$f":"I27+I26+2400","v":4139.9034798069597},{"$f":"G59+I37+(($I$26+$I$27)/1000)","v":5.873503479806959}]
[null,null,null,null,null,"Max. Burial Depth Check",{"$f":"IF(G61>=G57, \"Yes\",\"No\")","v":"Yes"}]
[null,null,null,null,null,"Min. Burial Depth Check",{"$f":"IF(G60<=G58, \"Yes\",\"No\")","v":"No"}]
[null,null,null,null,null,"Min height above chamber",{"$f":"ROUND(G58-((G26+G27))/12/Q3,1)","v":2.2999999999999998}]
[null,null,null,null,null,"Max height above chamber",{"$f":"ROUND(G57-((G26+G27))/12/Q3,1)","v":3.3}]
[null,null,null,null,null,"Liner calculations"]
[null,null,null,null,null,"Liner Length",{"$f":"IF(A19=1,\"\",IF('LB Calcs'!A20<=1,\"\",IF('LB Calcs'!A4=4,ROUNDUP(('LB Calcs'!G20+Tables!G29+'LB Calcs'!G35*2),0),IF('LB Calcs'!A4=3,ROUNDUP(('LB Calcs'!G20+Tables!G30+'LB Calcs'!G35*2),0),IF('LB Calcs'!A4=2,ROUNDUP(('LB Calcs'!G20+Tables!G31+'LB Calcs'!G35*2),0),ROUNDUP(('LB Calcs'!G20+Tables!G32+'LB Calcs'!G35*2),0))))))","v":""},"ft",{"$f":"IF(G67=\"\",\"\",G67/$Q$3)","v":""}]
[null,null,null,null,null,"Liner Width Before Adjusment",{"$f":"IF(A19=1,\"\",IF('LB Calcs'!A20<=1,\"\",IF('LB Calcs'!A4=4,ROUNDUP(('LB Calcs'!G21+Tables!G29+'LB Calcs'!G35*2),0),IF('LB Calcs'!A4=3,ROUNDUP(('LB Calcs'!G21+Tables!G30+'LB Calcs'!G35*2),0),IF('LB Calcs'!A4=2,ROUNDUP(('LB Calcs'!G21+Tables!G31+'LB Calcs'!G35*2),0),ROUNDUP(('LB Calcs'!G21+Tables!G32+'LB Calcs'!G35*2),0))))))","v":""},"ft",{"$f":"IF(G68=\"\",\"\",G68/$Q$3)","v":""}]
[null,null,null,null,null,"Liner Width Adjusment Factor",{"$f":"IF(A19=1,\"\",IF(A20<=1,\"\",ROUNDUP(IF(A20=2,G68/Tables!D29,IF(A20=3,G68/Tables!D30,IF(A20=4,G68/Tables!D31,IF(A20=5,G68/Tables!D32,IF(A20=6,G68/Tables!D33))))),0)))","v":""},"ft",""]
[null,null,null,null,null,"Final Liner Width",{"$f":"IF(A19=1,\"\",IF(A20<=1,\"\",IF(A20=2,G69*Tables!D29,IF(A20=3,G69*Tables!D30,IF(A20=4,G69*Tables!D31,IF(A20=5,G69*Tables!D32,IF(A20=6,G69*Tables!D33)))))))","v":""},"ft",""]
[null,null,null,null,null,"Liner Area",{"$f":"IF(A19=1,\"\",IF(A20<=1,\"\",G67*G70))","v":""},"sf",{"$f":"IF(G71=\"\",\"\",G71/$Q$7)","v":""}]

{"sheet":"Draft","index":3,"n_rows":24,"n_cols":19,"rows_kept":24,"cut":false,"hidden":true,"merged":[]}
[]
[]
["Chamber Size",null,null,null,null,null,null,"Number of Chambers",null,null,null,null,null,null,null,null,"Metric",null,1]
["Required Storage Volume",null,null,null,null,null,null,"Number of End Caps",null,null,null,null,null,null,null,null,"Standard",null,1]
["Bed size controlled by Length or Width?",null,null,null,null,null,null,"Bed Size (Including Perimiter Stone) "]
["Limiting Width or Length dimension",null,null,null,null,null,null,"Stone Required (Including Perimeter Stone)"]
["Stone Porosity",null,null,null,null,null,null,"Volume of Excavation"]
["Stone Above Chambers",null,null,null,null,null,null,"Non-Woven Filter Fabric Required (20% Safety Factor)"]
["Stone Foundation Depth",null,null,null,null,null,null,"Length of Isolator Row"]
["Average Cover Over Chambers",null,null,null,null,null,null,"Woven Isolator Row Fabric (20% Safety Factor)",null,null,null,null,null,null,null,null,null,"m2"]
[]
[]
[null,null,null,null,null,null,null,"Installed Storage Volume"]
[null,null,null,null,null,null,null,"Storage Volume per Chamber"]
[null,null,null,null,null,null,null,"Storage Volume per End Cap "]
[]
[]
["Maximum Length"]
[]
[null,"Rows of",null,"Chambers"]
[null,"Row of",null,"Chambers"]
[]
["Maximum Length"]
["Maximum Width"]

{"sheet":"Tables","index":4,"n_rows":33,"n_cols":25,"rows_kept":33,"cut":false,"hidden":true,"merged":[[0,19,0,22]]}
[null,null,"WC",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Values below based on Pipe Gallery 4.9 (2025)"]
[null,null,"System Size","ID (IN)","OD (IN)","Manifold C/C Spacing (IN)","Column Width (FT)","Edge Dist. (FT)","Bedding (in)","ID Storage Capacity (CF/FT)","Tee Width (IN)","ID Volume of Tee (CF)","OD Volume Displacement of Tee (CF)","90 Stub \n(Center to End)\n(IN)","ID Volume of 90 Elbow (CF)","Tee System Length (in)","Displacement \nSQFT","Tee Stub Length (IN)","OD Volume Displacement (CF/FT)","HS31 Endcap Stub Length (in)","HS75 Endcap Stub Length (in)","HS180 Endcap Stub Length (in)","HS290 Endcap Stub Length (in)"]
[null,1,12,12.076499999999999,14.616000000000001,25.190799999999999,0.8873833333333333,0.66666666666666663,4,0.79476437395892852,23.52,{"$f":"J3*((R3+K3)/12)","v":1.8584240277739612},{"$f":"(((E3^2)*PI()/4)/144)*((K3+R3)/12)","v":2.7245255100221986},11.76,{"$f":"J3*(N3*2/12)","v":1.5577381729594999},18.989999999999998,{"$f":"((E3^2)*PI()/4)/144","v":1.1651570249560363},{"$f":"4.54","v":4.54},1.0796201537103782,7.46,9.2799999999999994,10.119999999999999,11.62,null,{"$f":"T3+R3+E3","v":26.616}]
[null,2,15,15.15,17.79,27.7136,0.81824999999999992,0.66666666666666663,4,1.2497635473103432,28.71,{"$f":"J4*((R4+K4)/12)","v":3.5670334579482712},{"$f":"(((E4^2)*PI()/4)/144)*((K4+R4)/12)","v":4.9267283320566726},14.36,{"$f":"J4*(N4*2/12)","v":2.9911007565627545},23.17,{"$f":"((E4^2)*PI()/4)/144","v":1.7261529922534329},{"$f":"5.54","v":5.54},1.6073477140742691,0,9.2799999999999994,10.119999999999999,11.62]
[null,3,18,18.084499999999998,21.363500000000002,32.748199999999997,0.9402083333333332,0.75,4,1.7828105086178345,35.35,6.2873783937255636,{"$f":"(((E5^2)*PI()/4)/144)*((K5+R5)/12)","v":8.7788294578603914},17.7,5.2592910004226114,28.38,2.4892711128148557,{"$f":"6.97","v":6.97},2.3472077548213734,0,9.2799999999999994,10.119999999999999,11.62]
[null,4,24,24.36,28.145,47.136000000000003,1.5859833333333337,0.83333333333333337,4,3.2267200013705724,47.14,15.235496273138052,20.399767579017659,23.6,12.691765338724252,37.619999999999997,4.3204590707414736,{"$f":"9.52","v":9.52},4.0879963224928302,0,9.2799999999999994,10.119999999999999,11.62]
[null,5,30,29.872,34.674999999999997,54.991999999999997,1.6978083333333334,1.5,4,4.8668701106731476,54.99,26.435216151139652,35.619960936108811,27.5,22.306488007251925,44.81,6.5578326362888255,{"$f":"10.19","v":10.19},6.2147495195340881,0,null,10.119999999999999]
[null,6,36,35.46,40.5,61.463999999999999,1.7321749999999998,1.5,4,6.8409813640721708,61.31,40.817855472297282,53.378849864529386,30.7,35.003021312835941,13.5,8.9461759549490605,{"$f":"10.29","v":10.29},8.5318927428027216,0]
[null,7,0,0,0,0,0,0,0,{"$f":"(((D9/2)^2)*PI())/144","v":0},0,0,0,0,0,0,0,0,{"$f":"((E9^2)*PI()/4)/144","v":0},0]
[null,8,8,7.9675000000000002,9.6199999999999992,null,null,null,4,0.36699999999999999,19.600000000000001,0.75204416666666674,{"$f":"(((E10^2)*PI()/4)/144)*((K10+R10)/12)","v":1.0343197465757843},9.8000000000000007,0.59943333333333337,14.61,0.50475140133832497,4.99,0.46,7.01]
[null,9,10,10.15,11.87,94.2,2.28125,1.5,4,0.56699999999999995,26.13,{"$f":"J11*((R11+K11)/12)","v":1.5720074999999996},{"$f":"(((E11^2)*PI()/4)/144)*((K11+R11)/12)","v":2.1305924415907782},13.07,1.2351149999999997,18.989999999999998,{"$f":"((E11^2)*PI()/4)/144","v":0.76847337839162444},7.14,0.70799999999999996,4.8600000000000003]
[null,10,1,2,3,4,5,6,7,8,9,10,11,12,13,14,15,16,17,18,19,20,21]
[null,11,"Chamber"]
[null,null,"Chamber Size","Chamber Height (in)","Chamber Width (in)","Chamber Length (installed) (in)","Manifold C/C Spacing (FT)","Chamber Spacing (in)","Edge Dist from edge of chamber. (in)","End Dist from edge of endcap (in)","Bedding (in)","Height of Embedment above Chamber (in)","Min. Initial Backfill Height (in)","Sediment Width (ft)","Storage Capacity (CF/Chamber)","Length of End Cap (in)","End Cap Storage (CF)","Sediment Width (ft)","Max cover (ft)"]
[null,null,"HS31",16,34,85.5,39.9,3,12,12,6,6,16,{"$f":"4+(2/12)","v":4.166666666666667},15.14,6.88,0.62,4.1660000000000004,8]
[null,null,"HS75",29.73,51,84.9,{"$f":"E16+H16","v":57},6,12,12,6,6,18,5,46.6,10.44,3.4,5,8]
[null,1,"HS180",45.48,77.8,85.3,{"$f":"E17+H17","v":82.8},5,12,12,9,12,18,7.5,113.57,22.1,15.33,7.5,8]
[null,2,"HS290",{"$f":"80.5-12-9","v":59.5},100.5,48.3,109,8.5,12,12,9,12,24,9.75,109.67,32.360700000000001,39.6,9.75,7]
[null,3,1,2,3,4,5,6,7,8,9,10,11,12,13,14,15]
[null,4]
[null,null,null,"pink is update to spacing and cover for HS31 2025"]
[]
[]
[3]
["6 inches","Confirm distance between end cap & manifold on table"]
[null,"Confirm width of manifold on table"]
[null,"Confirm extra trench length after manifold"]
[null,null,"Liner Mesh","Increments",null,"Chamber","Fudge Factor"]
[null,null,10,7,null,"HS31",8]
[null,null,20,7,null,"HS75",13]
[null,null,30,7,null,"HS180",16]
[null,null,40,7,null,"HS290",19]
[null,null,60,5]

{"sheet":"Pics","index":5,"n_rows":1,"n_cols":10,"rows_kept":1,"cut":false,"hidden":true,"merged":[]}
[null,null,null,null,null,null,null,null,{"$f":"IF('LB Calcs'!$C$6=1,\"ONEMANIFOLD\",\"TWOMANIFOLDS\")","v":"TWOMANIFOLDS"},{"$f":"IF('LB Calcs'!$C$6=1,\"ONEMANIFOLD\",\"TWOMANIFOLDS\")","v":"TWOMANIFOLDS"}]

{"sheet":"Versions","index":6,"n_rows":23,"n_cols":6,"rows_kept":23,"cut":false,"hidden":true,"merged":[]}
[]
[null,null,"Version","Date","Action","Editor"]
[null,null,4.3,"2019-11-18","Endcap volumes where updated on the Tables Tab and one place in the VBA coding ","Sam Ewald"]
[null,null,4.4000000000000004,"2019-11-29","Coding on VBA changed so the Volume-Based tab didn't error-out when switching from standard to metric","Sam Ewald"]
[null,null,null,null,"Print area adjusted so only one page prints"]
[null,null,null,null,"New Logos added"]
[null,null,4.5,null,"Minor changes? (SPEL Version)","Sam Ewald"]
[null,null,4.5999999999999996,"2020-03-18","VBA Coding Module1 Changes","Sam Ewald"]
[null,null,null,null,"Case \"Metric\""]
[null,null,null,null,"From: \"syconversion = 0.1111\""]
[null,null,null,null,"  To:  \"syconversion = 0.83612\""]
[null,null,null,null,"From: \" cyconversion = 0.037037\""]
[null,null,null,null,"To: \"cyconversion = 0.76455\""]
[null,null,4.7,"2020-03-23","Corrected units workbook \"volume-based\" cell W14"]
[null,null,5.0999999999999996,"2020-09-17","Added in HS31 and HS290 with HS290 turned off until product release"]
[null,null,null,null,"Lots of changes to calcs, inputs, exports modified at this time","Sam Ewald"]
[null,null,5.2,"2020-09-21","Changed some formulas in Layout-based calculator to solve \"#REF\" issues with referencing manifold diamter","Sam Ewald "]
[null,null,5.3,"2020-10-01","Fixed print view on layout-based calculator ","Sam Ewald"]
[null,null,5.4,"2020-10-12","Fixed metric for layout-based manifold volume quantities","Sam Ewald"]
[null,null,5.8,"2021-02-08","Added HS290 functions","Sam Ewald"]
[null,null,5.9,"2021-09-30","Changed row spacing for HS180 from 8\" to 6\" and cover heights from 24\" to 18\".","Sam Ewald"]
[null,null,6.2,"2022-07-14","LB Calc: Trench length coding changed; now if there's 0 manifolds, it adds 2*end stone (usually 2'). If 1 man, 1 end stone+ 1 ft extra (2'). If 2 man, 2 ft extra.  Was adding 2' in all scenarios even though HS180 has less spacing.\nVB Calc: Changed min cover for HS180 from 24\" to 18\". Trenchlength now changed to =side1 as this is calculated using varying endcaptotrench variable instead of previous calculation adding 2' to systemlength. Accounts for HS180 difference in spacing of 6\" compared to 12\" for all other chambers. \nAlso NOTE: made calculator faster by going on Layout-Based Calculator tab>Find & Select>Selection pane. Then select all extra images hidden behind the top view image. Do this when copying or creating new versions as it seems to duplicate images each time a version is copied.","Amelie Dulas"]
[null,null,6.6,"2026-04-08","LB Calc: Added thermoplastic liner calculations and updated geotextile equations to match systems calc 6.6, combined scour and sediment row geotextile to just show as woven geotextile to match systems calc. Updated pipe and chamber values to match the chamber specs\nVB Calc: Added thermoplastic liner calculations and updated geotextile equations to match systems calc 6.6, combined scour and sediment row geotextile to just show as woven geotextile to match systems calc. Updated pipe and chamber values  to match the chamber specs\n","Bryce Erickson"]